{"id":7109,"date":"2026-04-13T09:09:48","date_gmt":"2026-04-13T12:09:48","guid":{"rendered":"https:\/\/www2.uepg.br\/elos\/?p=7109"},"modified":"2026-08-20T18:04:35","modified_gmt":"2026-08-20T21:04:35","slug":"vii-ciclo-descomemorar-golpes-contou-com-a-exibicao-do-documentario-40-anos-do-movimento-diretas-ja-em-ponta-grossa","status":"publish","type":"post","link":"https:\/\/www2.uepg.br\/elos\/vii-ciclo-descomemorar-golpes-contou-com-a-exibicao-do-documentario-40-anos-do-movimento-diretas-ja-em-ponta-grossa\/","title":{"rendered":"VII Ciclo Descomemorar Golpes contou com a exibi\u00e7\u00e3o do document\u00e1rio 40 anos do movimento Diretas J\u00e1 em Ponta Grossa"},"content":{"rendered":"<p style=\"text-align: center\"><em>Evento relembrou o in\u00edcio do movimento Diretas J\u00e1 no munic\u00edpio de Ponta Grossa<\/em><\/p>\n<pre style=\"text-align: center\">Por Maith\u00ea Galdino e Julia Smaka<\/pre>\n<p style=\"text-align: justify\">Na tarde da \u00faltima ter\u00e7a-feira (7), na sala A17 do Campus Central da Universidade Estadual de Ponta Grossa (UEPG), foi realizada a exibi\u00e7\u00e3o do document\u00e1rio \u201c40 anos do movimento Diretas J\u00e1 em Ponta Grossa\u201d. A produ\u00e7\u00e3o, desenvolvida em 2024 pela Ag\u00eancia de Jornalismo em parceria com o projeto de extens\u00e3o Combate \u00e0 Desinforma\u00e7\u00e3o nos Campos Gerais, resgata momentos marcantes da mobiliza\u00e7\u00e3o pela redemocratiza\u00e7\u00e3o no munic\u00edpio.<\/p>\n<p style=\"text-align: justify\">O document\u00e1rio relembra o in\u00edcio das articula\u00e7\u00f5es locais, destacando reuni\u00f5es ocorridas em 1983 na C\u00e2mara Municipal, que contribu\u00edram para o fortalecimento do movimento entre o final daquele ano e janeiro de 1984. A obra evidencia a uni\u00e3o entre partidos pol\u00edticos, sindicatos e estudantes, al\u00e9m da distribui\u00e7\u00e3o de panfletos que estimularam a participa\u00e7\u00e3o popular naquele per\u00edodo na cidade. Mesmo sob a ditadura e diante de persegui\u00e7\u00f5es, o movimento manteve car\u00e1ter pac\u00edfico e contou com significativa participa\u00e7\u00e3o da popula\u00e7\u00e3o pontagrossense.<\/p>\n<p style=\"text-align: justify\">Para David C\u00e2ndido, jornalista e doutorando no Programa de P\u00f3s-Gradua\u00e7\u00e3o em Jornalismo da UEPG, a exibi\u00e7\u00e3o do document\u00e1rio \u00e9 relevante para ampliar os debates sobre o tema. \u201cEu acredito que as discuss\u00f5es sobre as Diretas J\u00e1 e outros movimentos pol\u00edticos ligados \u00e0 ditadura muitas vezes ficam restritas a determinados espa\u00e7os, sendo importante promover essa expans\u00e3o\u201d, afirmou.<\/p>\n<p style=\"text-align: justify\">A discuss\u00e3o sobre os desafios da democracia integra o VII Ciclo Descomemorar Golpes: \u201cInformar, Educar e Resistir em Tempos de Desinforma\u00e7\u00e3o\u201d, realizado de 6 a 13 de abril na UEPG, com atividades distribu\u00eddas nos campi Central e Uvaranas. A programa\u00e7\u00e3o re\u00fane debates, exibi\u00e7\u00f5es e encontros voltados \u00e0 reflex\u00e3o cr\u00edtica sobre o cen\u00e1rio democr\u00e1tico, com participa\u00e7\u00e3o aberta ao p\u00fablico e inscri\u00e7\u00f5es gratuitas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento relembrou o in\u00edcio do movimento Diretas J\u00e1 no munic\u00edpio de Ponta Grossa Por Maith\u00ea Galdino e Julia Smaka Na tarde da \u00faltima ter\u00e7a-feira (7), na sala A17 do Campus Central da Universidade Estadual de Ponta Grossa (UEPG), foi realizada a exibi\u00e7\u00e3o do document\u00e1rio \u201c40 anos do movimento Diretas J\u00e1 em Ponta Grossa\u201d. A produ\u00e7\u00e3o,&nbsp;&hellip;<\/p>\n","protected":false},"author":846,"featured_media":7110,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts\/7109"}],"collection":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/users\/846"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/comments?post=7109"}],"version-history":[{"count":1,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts\/7109\/revisions"}],"predecessor-version":[{"id":7111,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts\/7109\/revisions\/7111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/media\/7110"}],"wp:attachment":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/media?parent=7109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/categories?post=7109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/tags?post=7109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}