{"id":7193,"date":"2026-05-09T18:04:47","date_gmt":"2026-05-09T21:04:47","guid":{"rendered":"https:\/\/www2.uepg.br\/elos\/?p=7193"},"modified":"2026-08-20T18:08:14","modified_gmt":"2026-08-20T21:08:14","slug":"v-forum-municipal-dos-direitos-da-mulher-debate-violencia-e-elege-nova-composicao-do-conselho","status":"publish","type":"post","link":"https:\/\/www2.uepg.br\/elos\/v-forum-municipal-dos-direitos-da-mulher-debate-violencia-e-elege-nova-composicao-do-conselho\/","title":{"rendered":"V F\u00f3rum Municipal dos Direitos da Mulher debate viol\u00eancia e elege nova composi\u00e7\u00e3o do conselho"},"content":{"rendered":"<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Al\u00e9m da vota\u00e7\u00e3o que definiu as representantes do conselho para a gest\u00e3o 2026 a 2028, a programa\u00e7\u00e3o teve discuss\u00f5es sobre o papel da justi\u00e7a e o impacto do luto e da mem\u00f3ria em casos de feminic\u00eddio\u00a0<\/span><\/i><\/p>\n<pre><i><span style=\"font-weight: 400\">por: Leonardo Correia \r\n<\/span><\/i><\/pre>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Representantes de diversos setores da sociedade e do poder p\u00fablico se reuniram ontem (08) no audit\u00f3rio do Sindicato dos Servidores P\u00fablicos Municipais de Ponta Grossa (SindServ &#8211; PG) para o V F\u00f3rum Municipal dos Direitos da Mulher e da Elei\u00e7\u00e3o das Entidades n\u00e3o governamentais do Conselho Municipal dos Direitos da Mulher de Ponta Grossa (CMDM &#8211; PG).\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A mesa de abertura do evento foi formada pela presidenta do CMDM &#8211; PG, Andrea Marques, e pela secret\u00e1ria municipal da Fam\u00edlia e do Desenvolvimento Social, Camila Calisto Sanches, que na ocasi\u00e3o representtou a prefeita Elizabeth Schmidt. Tamb\u00e9m estiveram presentes a vereadora Marisleidy Rama, da Procuradoria da Mulher, e a dra. Aniele Santana, do 2\u00ba Juizado Especial de Viol\u00eancia Dom\u00e9stica, representando o poder judici\u00e1rio. Compuseram a mesa ainda a presidenta da OAB de Ponta Grossa, dra. Maria Antonieta, Izabel Ribas representando a deputada estadual Mabel Canto e Ang\u00e9lica Mendes do Sindicato dos Servidores P\u00fablicos Municipais. A composi\u00e7\u00e3o foi completada pela presidenta da comiss\u00e3o organizadora do F\u00f3rum, \u00cdndia Mara de Souza Holleben, e a professora Dra. Silvana Mariano, da Universidade Estadual de Londrina.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Cada convidada explicou a import\u00e2ncia de compor a mesa como mulher representando suas respectivas fun\u00e7\u00f5es nas institui\u00e7\u00f5es de Ponta Grossa e destacou o F\u00f3rum Municipal dos Direitos da Mulher como um espa\u00e7o fundamental para transformar vozes individuais em for\u00e7a coletiva.\u00a0 O papel do Conselho como lugar seguro para denunciar abusos, debater desigualdades, propor e fiscalizar pol\u00edticas p\u00fablicas que garantam seguran\u00e7a e autonomia tamb\u00e9m ganhou destaque.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Antes da palestra da professora Dra. Silvana Mariano, tamb\u00e9m foram realizadas homenagens a conselheiras que faleceram nos \u00faltimos dois anos, como forma de reconhecimento pela contribui\u00e7\u00e3o na luta pelos direitos das mulheres no munic\u00edpio.\u00a0\u00a0<\/span><\/p>\n<pre><i><span style=\"font-weight: 400\">\u00a0<\/span><\/i><\/pre>\n<p style=\"text-align: justify\"><b>Feminic\u00eddio e Justi\u00e7a: Punir \u00e9 Suficiente?<\/b><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A professora Silvana Mariano possui experi\u00eancia na \u00e1rea de Sociologia com \u00eanfase em estudos de g\u00eanero e atua principalmente em temas como feminismo, pol\u00edticas p\u00fablicas, cidadania e o enfrentamento ao feminic\u00eddio. A palestrante iniciou a exposi\u00e7\u00e3o com o questionamento: &#8220;Quando o Sistema Responde ao Feminic\u00eddio: A quem ele est\u00e1 servindo?\u201d. Durante a fala, ela reproduziu o trecho de um \u00e1udio de sua irm\u00e3 Cidin\u00e9ia Mariano, v\u00edtima de feminic\u00eddio. \u201cEu quero seguir em frente, eu quero erguer a cabe\u00e7a, levantar cedo, trabalhar e cuidar dos meus filhos, como eu sempre fiz. A \u00fanica coisa que eu quero \u00e9 paz\u201d. O relato revela o sofrimento da v\u00edtima e exp\u00f5e o sofrimento de familiares diante da perda.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A palestrante revelou que, no Paran\u00e1, entre 2020 e 2024 foram analisados 858 processos judiciais de feminic\u00eddio com 899 r\u00e9us e 934 v\u00edtimas entre casos consumados e tentados. Os dados s\u00e3o retirados do Laborat\u00f3rio de Estudos de Feminic\u00eddios (LESFEM), um espa\u00e7o de pesquisa interdisciplinar que re\u00fane pesquisadoras e pesquisadores, profissionais e estudantes da Universidade Estadual de Londrina (UEL), Universidade Federal de Uberl\u00e2ndia (UFU), Universidade Federal da Bahia (UFBA), Coletivo Feminino Plural (CFP) e Secretaria Municipal de Pol\u00edticas para Mulheres de Londrina (SMPM). O objetivo do Laborat\u00f3rio \u00e9 produzir e analisar dados sobre crimes de feminic\u00eddios, consumados e tentados, no Brasil, contribuindo para o monitoramento e visibiliza\u00e7\u00e3o do fen\u00f4meno e para a melhoria da qualidade das estat\u00edsticas oficiais e da resposta da sociedade e do Estado ao enfrentamento \u00e0 viol\u00eancia contra mulheres e meninas, considerando os tr\u00eas pilares dessa pol\u00edtica: preven\u00e7\u00e3o, puni\u00e7\u00e3o e restitui\u00e7\u00e3o de direitos. Confira dados, pesquisas e levantamentos do LESFEM clicando <\/span><a href=\"https:\/\/sites.uel.br\/lesfem\/\"><span style=\"font-weight: 400\">[AQUI]<\/span><\/a><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Silvana Mariano ressaltou, com base nos dados, que a condena\u00e7\u00e3o do agressor n\u00e3o desfaz o que aconteceu: \u201cA condena\u00e7\u00e3o \u00e9 uma resposta ao crime que j\u00e1 aconteceu. O que n\u00f3s queremos \u00e9 que o crime n\u00e3o aconte\u00e7a\u201d.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A palestrante considera que os crimes revelam marcas enraizadas de poder, controle e puni\u00e7\u00e3o e menciona a <\/span><span style=\"font-weight: 400\">edi\u00e7\u00e3o 2025 do Memorial de V\u00edtimas de Feminic\u00eddio no Paran\u00e1, <\/span><a href=\"https:\/\/sites.uel.br\/lesfem\/memorial-de-vitimas-de-feminicidio-no-parana\/memorial-de-vitimas-de-feminicidio-no-parana-2025\/\"><span style=\"font-weight: 400\">\u201cA Falta que Faz\u201d<\/span><\/a><span style=\"font-weight: 400\">, com o registro de 122 casos consumados no estado. A publica\u00e7\u00e3o se soma ao debate nacional sobre luto e mem\u00f3ria, refor\u00e7ado pela Lei Federal <\/span><a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2026\/lei-15334-8-janeiro-2026-798640-publicacaooriginal-177738-pl.html\"><span style=\"font-weight: 400\">n\u00ba 15.334\/2026<\/span><\/a><span style=\"font-weight: 400\">, que instituiu o Dia Nacional de Luto e Mem\u00f3ria \u00e0s Mulheres V\u00edtimas de Feminic\u00eddio, celebrado em 17 de outubro.<\/span><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Durante o debate com o p\u00fablico, a professora foi indagada sobre acompanhamentos com recortes espec\u00edficos como surdez e mulheres trans. \u201cNesse caso n\u00e3o \u00e9 o dado que vai falar, mas sim a aus\u00eancia que vai gritar\u201d, observa, destacando a necessidade de aprimoramento da rede de enfrentamento \u00e0 viol\u00eancia.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Como as pesquisas utilizam materiais jornal\u00edsticos, a palestrante tamb\u00e9m pontuou que muitas vezes as mortes de mulheres trans s\u00e3o retratadas de forma rasa nos jornais. \u201cA imprensa \u00e9 uma parceria fundamental nesse trabalho de ressignifica\u00e7\u00e3o das hist\u00f3rias, de como falar sobre viol\u00eancia e retratar mulheres\u201d. Ela acredita que o espa\u00e7o de di\u00e1logo com o jornalismo contribui para a mudan\u00e7a na abordagem de casos de viol\u00eancia.<\/span><\/p>\n<pre><i><span style=\"font-weight: 400\">\u00a0<\/span><\/i><\/pre>\n<p style=\"text-align: justify\"><b>Elei\u00e7\u00e3o das Entidades n\u00e3o governamentais do CMDM<\/b><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">No per\u00edodo da tarde ocorreu a elei\u00e7\u00e3o para a nova composi\u00e7\u00e3o do Conselho Municipal dos Direitos da Mulher de Ponta Grossa com a inscri\u00e7\u00e3o de 15 entidades da sociedade civil que prop\u00f5em a continuidade em pautas de prote\u00e7\u00e3o e empoderamento feminino no munic\u00edpio. As entidades vencedoras assumem uma gest\u00e3o de dois anos para o per\u00edodo de 2026 a 2028.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Inicialmente, houve a apresenta\u00e7\u00e3o obrigat\u00f3ria de tr\u00eas minutos para cada entidade com as propostas para a nova gest\u00e3o, em conformidade com o previsto no regulamento das elei\u00e7\u00f5es. Como a Uni\u00e3o por Moradia Popular de Ponta Grossa e Regi\u00e3o (UMPPG) n\u00e3o cumpriu este requisito, acabou desclassificada da elei\u00e7\u00e3o. Participaram da vota\u00e7\u00e3o 14 entidades e o resultado foi disponibilizado no mesmo dia.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">As entidades que assumem as dez vagas da sociedade civil no conselho s\u00e3o: <\/span><span style=\"font-weight: 400\">Associa\u00e7\u00e3o Comercial, Industrial e Empresarial de Ponta Grossa<\/span> <span style=\"font-weight: 400\">\u00a0(ACIPG), Associa\u00e7\u00e3o Flor de Liz LGBT, Associa\u00e7\u00e3o Garagem Mulher, Associa\u00e7\u00e3o Uni\u00e3o das Mulheres dos Campos Gerais (AUMCG), <\/span><span style=\"font-weight: 400\">Conselho Regional de Servi\u00e7o Social (<\/span><span style=\"font-weight: 400\">CRESS 11\u00ba), Instituto Cidade Viva, Instituto Sorriso Negro, Instituto Uni\u00e3o das Mulheres em A\u00e7\u00e3o e Desenvolvimento (IUMAD), Santa Casa de Ponta Grossa e <\/span><span style=\"font-weight: 400\">Se\u00e7\u00e3o Sindical dos Docentes da Universidade Estadual de Ponta Grossa<\/span><span style=\"font-weight: 400\"> (SINDUEPG).<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Na supl\u00eancia, ficaram as entidades Sociedade Espiritualista Caboclos da Lei, Sindicato Rural e Associa\u00e7\u00e3o dos Usu\u00e1rios de Transportes Coletivos Urbanos, Rodovi\u00e1rias, Ferrovi\u00e1rios, Metrovi\u00e1rios, T\u00e1xis, Moto T\u00e1xis e A\u00e9reos de Ponta Grossa (AUTRANS).<\/span><\/p>\n<pre><i><span style=\"font-weight: 400\">\u00a0<\/span><\/i><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00e9m da vota\u00e7\u00e3o que definiu as representantes do conselho para a gest\u00e3o 2026 a 2028, a programa\u00e7\u00e3o teve discuss\u00f5es sobre o papel da justi\u00e7a e o impacto do luto e da mem\u00f3ria em casos de feminic\u00eddio\u00a0 por: Leonardo Correia Representantes de diversos setores da sociedade e do poder p\u00fablico se reuniram ontem (08) no audit\u00f3rio&nbsp;&hellip;<\/p>\n","protected":false},"author":846,"featured_media":7194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts\/7193"}],"collection":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/users\/846"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/comments?post=7193"}],"version-history":[{"count":1,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts\/7193\/revisions"}],"predecessor-version":[{"id":7195,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/posts\/7193\/revisions\/7195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/media\/7194"}],"wp:attachment":[{"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/media?parent=7193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/categories?post=7193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.uepg.br\/elos\/wp-json\/wp\/v2\/tags?post=7193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}