{"id":3205,"date":"2026-04-14T16:49:59","date_gmt":"2026-04-14T19:49:59","guid":{"rendered":"https:\/\/www2.uepg.br\/periodico\/?p=3205"},"modified":"2026-08-27T10:51:01","modified_gmt":"2026-08-27T13:51:01","slug":"critica-de-ponta-160","status":"publish","type":"post","link":"https:\/\/www2.uepg.br\/periodico\/critica-de-ponta-160\/","title":{"rendered":"Cr\u00edtica de Ponta #160"},"content":{"rendered":"<h1><img loading=\"lazy\" class=\"wp-image-3222 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/critica-de-ponta-newsletter.jpg-300x169.jpeg\" alt=\"\" width=\"466\" height=\"262\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/critica-de-ponta-newsletter.jpg-300x169.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/critica-de-ponta-newsletter.jpg-1024x576.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/critica-de-ponta-newsletter.jpg-768x432.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/critica-de-ponta-newsletter.jpg-1232x693.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/critica-de-ponta-newsletter.jpg.jpeg 1280w\" sizes=\"(max-width: 466px) 100vw, 466px\" \/><\/h1>\n<h1 style=\"text-align: center\">Cr\u00edtica de Ponta<\/h1>\n<p style=\"text-align: center\">Produzido pelo terceiro ano do curso de Jornalismo da UEPG, o Cr\u00edtica de Ponta traz o melhor da cultura da cidade de Ponta Grossa para voc\u00ea!<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-3220 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4573.JPG-1-300x178.jpeg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4573.JPG-1-300x178.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4573.JPG-1-1024x606.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4573.JPG-1-768x455.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4573.JPG-1-1232x729.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4573.JPG-1.jpeg 1399w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center\"><b>\u201cAinda assim, eu me levanto\u201d<\/b><\/p>\n<p style=\"text-align: center\"><em><span style=\"font-weight: 400\">Levante de Lilah Halla exp\u00f5e realidade do direito ao aborto no Brasil<\/span><\/em><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O primeiro filme da diretora de cinema brasileira Lillah Halla discute um dos temas da atualidade: o aborto. Dados do DATASUS 2021 apontam que para cada aborto legal realizado no Paran\u00e1, o SUS atende 279 mulheres por procedimentos malsucedidos. Uma mulher a cada dois dias morre por aborto inseguro no <\/span><a href=\"https:\/\/abortonobrasil.info\/#\"><span style=\"font-weight: 400\">Brasil<\/span><\/a><span style=\"font-weight: 400\">, e a criminaliza\u00e7\u00e3o n\u00e3o impede que um milh\u00e3o de abortos induzidos ocorram todos os anos, segundo o Minist\u00e9rio da Sa\u00fade. \u2018Levante\u2019 de 2024 \u00e9 um retrato fiel do problema nas classes mais baixas do pa\u00eds.<\/span><\/p>\n<div id=\"attachment_3206\" style=\"width: 424px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3206\" loading=\"lazy\" class=\"wp-image-3206\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Los-Creditos_-Divulgacao_Festival-do-Rio-300x150.jpg\" alt=\"Foto: Divulga\u00e7\u00e3o\/Festival do Rio\" width=\"414\" height=\"207\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Los-Creditos_-Divulgacao_Festival-do-Rio-300x150.jpg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Los-Creditos_-Divulgacao_Festival-do-Rio-768x384.jpg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Los-Creditos_-Divulgacao_Festival-do-Rio.jpg 770w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/><p id=\"caption-attachment-3206\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o\/Festival do Rio<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Sofia (Ayomi Domenica) \u00e9 a estrela do time de v\u00f4lei C. Leste. Aos 17 anos, a jogadora recebe a not\u00edcia de que pode conseguir uma bolsa para jogar no Chile, o in\u00edcio de um futuro brilhante no esporte. No entanto, a descoberta de gravidez indesejada coloca o sonho em risco. A personagem n\u00e3o quer continuar com a gesta\u00e7\u00e3o, mas \u00e9 imposs\u00edvel interromper no Brasil sem ser caso de viol\u00eancia sexual, feto anenc\u00e9falo ou gravidez de risco.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O longa pontua a vis\u00e3o das minorias no acesso \u00e0 sa\u00fade p\u00fablica. Na hist\u00f3ria, \u00e9 uma mulher negra (Zora Santos) que convence o pai de Sofia (R\u00f4mulo Braga) a ajud\u00e1-la no aborto e que doa uma quantidade significativa de dinheiro para a realiza\u00e7\u00e3o do procedimento. J\u00e1 no hospital, \u00e9 uma m\u00e9dica negra (Rejane Faria) que cuida da protagonista. Dados da Pesquisa Nacional de Aborto, realizada em 2021, mostram que pretas e pardas t\u00eam 46% mais chances de fazer aborto inseguro e est\u00e3o mais expostas aos riscos decorrentes da criminaliza\u00e7\u00e3o. Com medo de repres\u00e1lias, muitas mulheres se recusam a procurar servi\u00e7os de sa\u00fade em casos de complica\u00e7\u00f5es, levando a hemorragias, esteriliza\u00e7\u00e3o involunt\u00e1ria e at\u00e9 \u00e0 morte.<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Amanda Los<\/em><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\"><strong>Servi\u00e7o<\/strong>: Com dura\u00e7\u00e3o de 1h 32m \u201cLevante\u201d \u00e9 uma coprodu\u00e7\u00e3o entre Brasil, Fran\u00e7a e Uruguai. Nos outros dois pa\u00edses, o aborto \u00e9 legalizado. Levante ganhou o Pr\u00eamio Fipresci no Festival de Cannes e o trof\u00e9u de Melhor Dire\u00e7\u00e3o no Festival do Rio. O longa est\u00e1 dispon\u00edvel nos servi\u00e7os de streaming Prime Video e Globoplay.<\/span><\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-3218 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4570.JPG-300x171.jpeg\" alt=\"\" width=\"300\" height=\"171\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4570.JPG-300x171.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4570.JPG-1024x584.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4570.JPG-768x438.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4570.JPG-1232x703.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4570.JPG.jpeg 1451w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center\"><b>Amor ou abuso?<\/b><\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Crescimento do dark romance no Brasil levanta debates sobre a romantiza\u00e7\u00e3o da viol\u00eancia nas narrativas<\/span><\/i><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O consumo de livros digitais cresceu no Brasil. No \u00faltimo ano, segundo dados da Amazon, o pa\u00eds teve uma m\u00e9dia de 1,7 bilh\u00e3o de p\u00e1ginas consumidas por m\u00eas. O subg\u00eanero liter\u00e1rio que lidera os <em>rankings<\/em> de leitura \u00e9 o <em>dark romance<\/em>. De acordo com \u00edndices da Amazon Brasil, o subg\u00eanero ficou entre os mais lidos em 2025, tendo um livro da categoria como o mais consumido no pa\u00eds. Conforme os indicadores disponibilizados pela <\/span><span style=\"font-weight: 400\"><a href=\"https:\/\/www.prolivro.org.br\/wp-content\/uploads\/2020\/07\/1815-1.pdf\">C\u00e2mara Brasileira do Livro<\/a>, <\/span><span style=\"font-weight: 400\">cerca de 93,4 milh\u00f5es de leitores leram ao menos um livro nos \u00faltimos tr\u00eas meses de 2025.<\/span><\/p>\n<div id=\"attachment_3207\" style=\"width: 219px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3207\" loading=\"lazy\" class=\"size-medium wp-image-3207\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Rafaella-Creditos_-Divulgacao-209x300.jpg\" alt=\"Foto: Divulga\u00e7\u00e3o\" width=\"209\" height=\"300\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Rafaella-Creditos_-Divulgacao-209x300.jpg 209w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Amanda-Rafaella-Creditos_-Divulgacao.jpg 696w\" sizes=\"(max-width: 209px) 100vw, 209px\" \/><p id=\"caption-attachment-3207\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">\u200e<em>Dark romanc<\/em>e, ou romance sombrio, \u00e9 um subg\u00eanero da literatura rom\u00e2ntica que explora rela\u00e7\u00f5es amorosas em contextos mais sombrios e, muitas vezes, moralmente complexos. A categoria aborda temas tabus, abusivos e moralmente question\u00e1veis em uma narrativa de amor intenso que, com frequ\u00eancia, n\u00e3o \u00e9 saud\u00e1vel integralmente para as protagonistas das tramas. Consumido pelo p\u00fablico jovem, a tem\u00e1tica entra em debate por ilustrar a viol\u00eancia como algo justific\u00e1vel se feita em prol do amor.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Com uma percep\u00e7\u00e3o amb\u00edgua, o subg\u00eanero fica em uma linha t\u00eanue entre a romantiza\u00e7\u00e3o da cultura da viol\u00eancia e a exposi\u00e7\u00e3o de uma realidade nada rom\u00e2ntica. No primeiro semestre de 2025, segundo a Secretaria de Seguran\u00e7a P\u00fablica do Estado do Paran\u00e1, Ponta Grossa registrou 290 casos de viol\u00eancia contra a mulher. A viol\u00eancia de g\u00eanero, particularmente o feminic\u00eddio, tem apresentado taxas mais altas em munic\u00edpios menores. No mesmo ano, segundo a <\/span><a href=\"https:\/\/www12.senado.leg.br\/institucional\/omv\/pesquisanacional\"><span style=\"font-weight: 400\">11\u00aa Pesquisa Nacional de Viol\u00eancia contra a Mulher,<\/span><\/a><span style=\"font-weight: 400\"> 3,7 milh\u00f5es de brasileiras declararam ter vivido epis\u00f3dios de viol\u00eancia dom\u00e9stica ou familiar. Tais dados exp\u00f5em uma realidade diferente do romance sombrio idealizado por esse subg\u00eanero.<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Amanda Rafaella<\/em><\/p>\n<p><strong>Servi\u00e7o<\/strong>: <span style=\"font-weight: 400\">Para denunciar situa\u00e7\u00f5es de viol\u00eancia contra mulher ligue 180 ou acesse o site da Pol\u00edcia Civil do Paran\u00e1.<\/span><\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-3216 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4571.JPG-300x168.jpeg\" alt=\"\" width=\"300\" height=\"168\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4571.JPG-300x168.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4571.JPG-1024x573.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4571.JPG-768x430.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4571.JPG-1232x689.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4571.JPG.jpeg 1410w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center\"><b>Sanguin\u00e1ria, feminismo entre o soprano e o contralto<\/b><\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Cantora ponta-grossense traz cr\u00edticas sociais em m\u00fasicas<\/span><\/i><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Em um cen\u00e1rio em que existe o avan\u00e7o do conservadorismo, artistas usam suas obras como um espa\u00e7o de protesto e debate pol\u00edtico. Mais Una Mulher, conhecida como \u201cMUM\u201d e pseud\u00f4nimo de Gabriela Cordeiro de Paula, \u00e9 uma das <\/span><a href=\"https:\/\/periodico.sites.uepg.br\/index.php\/critica-de-ponta-newsletter?contrast=highcontrast2\"><span style=\"font-weight: 400\">cantoras <em>indie<\/em> da cena local<\/span><\/a><span style=\"font-weight: 400\"> que faz parte desse desafio.<\/span><\/p>\n<div id=\"attachment_3208\" style=\"width: 378px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3208\" loading=\"lazy\" class=\" wp-image-3208\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Bruna-Creditos_-divulgacao--300x150.png\" alt=\"Foto: Divulga\u00e7\u00e3o\/MUM\" width=\"368\" height=\"184\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Bruna-Creditos_-divulgacao--300x150.png 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Bruna-Creditos_-divulgacao--768x384.png 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Bruna-Creditos_-divulgacao-.png 999w\" sizes=\"(max-width: 368px) 100vw, 368px\" \/><p id=\"caption-attachment-3208\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o\/MUM<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Visceral, o \u00e1lbum \u201cSanguin\u00e1ria\u201d, lan\u00e7ado em novembro de 2025, abre portas para questionar a santifica\u00e7\u00e3o do sagrado feminino e o seu uso como forma de repress\u00e3o contra as mulheres. Dor, ang\u00fastia, raiva e revolta. S\u00e3o esses os elementos que constroem parte do cotidiano de uma mulher em uma sociedade que est\u00e1 adoecida pelo patriarcado; Mum faz a den\u00fancia deles. \u00c9 a\u00ed que surge a premissa \u201csanguin\u00e1ria\u201d, que busca pela emancipa\u00e7\u00e3o feminina. \u201cNo peito de quem se entregou \u00e0 mar\u00e9 de azar, no rosto de quem sabe o que \u00e9 ser mais uma mulher\u201d. \u00c9 a\u00ed que se encontra a tradu\u00e7\u00e3o do sentimento de redu\u00e7\u00e3o de g\u00eanero, de apenas ser considerada uma estat\u00edstica aos moldes da sociedade.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">\u00c9 poss\u00edvel destacar que as composi\u00e7\u00f5es seguem teor m\u00edstico e se abra\u00e7a o discurso de que \u201csomos as bruxas que n\u00e3o conseguiram queimar\u201d. Em virtude, a constru\u00e7\u00e3o de um eu l\u00edrico profano e expl\u00edcito ajudou a compor essa linguagem de maneira densa, e n\u00e3o de modo que fosse apenas um recurso para ser utilizado nas entrelinhas. O instrumental pesado, ou ora leve algumas vezes, \u00e9 um componente que ajuda a expressar o \u00e2mago mais \u00edntimo no vocal. Esta \u00e9 a ess\u00eancia do \u00e1lbum, que n\u00e3o apenas se agarra em acordes graves e melanc\u00f3licos, e sim, na capacidade de mostrar versatilidade.<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Bruna Sluzala<\/em><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\"><strong>Servi\u00e7o<\/strong>: O \u00e1lbum possui 11 faixas e tem 34 minutos de dura\u00e7\u00e3o. Ele est\u00e1 dispon\u00edvel nas plataformas digitais <\/span><a href=\"https:\/\/www.youtube.com\/watch?v=TVjrAaJ0PVE&amp;list=OLAK5uy_nidoYq3ci_7ASof23_kPUuGMvkXsVZXK4\"><span style=\"font-weight: 400\">YouTube<\/span><\/a><span style=\"font-weight: 400\"> e <\/span><a href=\"https:\/\/open.spotify.com\/album\/0JkHSkKa4mQSAxN4uVbAjY?si=qa_Fi64KQ7SDPEGRtflyIg\"><span style=\"font-weight: 400\">Spotify<\/span><\/a><span style=\"font-weight: 400\">. Atualmente, \u00e9 o terceiro \u00e1lbum da cantora e traz os singles \u201cMais uma Mulher\u201d, \u201cParto para N\u00e3o Voltar\u201d, \u201cCarca\u00e7a\u201d e \u201cSangue\u201d. At\u00e9 o momento, \u201cMais uma Mulher\u201d possui 44 mil streams no Spotify.<\/span><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-3217 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4569.JPG-300x172.jpeg\" alt=\"\" width=\"239\" height=\"137\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4569.JPG-300x172.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4569.JPG-1024x587.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4569.JPG-768x440.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4569.JPG-1232x706.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4569.JPG.jpeg 1444w\" sizes=\"(max-width: 239px) 100vw, 239px\" \/><\/p>\n<p style=\"text-align: center\"><strong>Arte de papel\u00e3o com restos de tinta<\/strong><\/p>\n<p style=\"text-align: center\"><em><span style=\"font-weight: 400\">Artista ponta-grossense usa restos de tinta em formas que evocam rostos<\/span><\/em><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Sebasti\u00e3o Nat\u00e1lio utiliza o acaso como ponto de partida para a cria\u00e7\u00e3o. Durante a limpeza de pinc\u00e9is com nanquim, tinta escorre sobre papel\u00e3o e forma tra\u00e7os que sugerem rostos e figuras. Os vest\u00edgios deixam de ser res\u00edduos e passam a ser obras, em um processo que transforma restos que virariam lixos em imagens.<\/span><\/p>\n<div id=\"attachment_3209\" style=\"width: 346px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3209\" loading=\"lazy\" class=\" wp-image-3209\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais-300x200.jpg\" alt=\"Foto: Raissa Pais\" width=\"336\" height=\"224\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais-300x200.jpg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais-1024x683.jpg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais-768x512.jpg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais-1232x821.jpg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais-272x182.jpg 272w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Daniel-Americo-foto-Raissa-Pais.jpg 1368w\" sizes=\"(max-width: 336px) 100vw, 336px\" \/><p id=\"caption-attachment-3209\" class=\"wp-caption-text\">Foto: Raissa Pais<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O trabalho continua a partir dos tra\u00e7os de tinta. \u201cComecei a ver rostos nas manchas\u201d, explica o artista. Com caneta branca, formas s\u00e3o destacadas e reorganizadas, criando composi\u00e7\u00f5es que equilibram acaso e constru\u00e7\u00e3o consciente.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Jornalista e artista visual, Sebasti\u00e3o Nat\u00e1lio que j\u00e1 exp\u00f4s em diversos lugares da cidade, como por exemplo, mais recentemente na galeria da PROEX e na Central de Salas na UEPG Uvaranas em Ponta Grossa, desenvolve desde a d\u00e9cada de 1980 t\u00e9cnica de pintura em papel\u00e3o baseada no reaproveitamento de materiais. O uso do papel\u00e3o mant\u00e9m rela\u00e7\u00e3o direta com o processo, incorporando material descartado e aproximando a produ\u00e7\u00e3o do cotidiano urbano.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Mas \u00e9 justamente a\u00ed que aparece um ponto de cr\u00edtica. Ao dar tanto destaque ao processo que origina as imagens, algumas obras acabam dependendo mais da hist\u00f3ria de cria\u00e7\u00e3o do que da for\u00e7a visual que apresentam sozinhas. Em certos momentos, a imagem parece apenas acompanhar o que a mancha j\u00e1 indicava, sem avan\u00e7ar muito al\u00e9m disso. A tens\u00e3o entre processo e resultado acaba se tornando uma caracter\u00edstica dos trabalhos do artista.\u00a0<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Daniel Am\u00e9rico<\/em><\/p>\n<p style=\"text-align: justify\"><strong>Servi\u00e7o<\/strong>: <span style=\"font-weight: 400\">As obras foram apresentadas no dia 21 de mar\u00e7o de 2026, durante o evento <\/span><a href=\"https:\/\/www.instagram.com\/p\/DWMCPC0kTLU\/?igsh=cHVkaXlpb2h4YTRi\"><span style=\"font-weight: 400\">Museu no P\u00e1tio<\/span><\/a><span style=\"font-weight: 400\">, no Museu Campos Gerais, com valores entre R$30 e R$100.<\/span><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-3213 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4574.JPG-300x171.jpeg\" alt=\"\" width=\"244\" height=\"139\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4574.JPG-300x171.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4574.JPG-1024x584.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4574.JPG-768x438.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4574.JPG-1232x702.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4574.JPG.jpeg 1453w\" sizes=\"(max-width: 244px) 100vw, 244px\" \/><\/p>\n<p style=\"text-align: center\"><b>Dos requintes de Ponta Grossa<\/b><\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Bistr\u00f4 ponta-grossense reconhecido pelo jantar, agora atende em hor\u00e1rio de almo\u00e7o<\/span><\/i><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">J\u00e1 imaginou ir a um restaurante que existe a apenas seis anos no Paran\u00e1 e j\u00e1 se encontra na lista dos 30 melhores do estado? O Tomate Seco Bistr\u00f4 \u00e9 distinto pelos vinhos, gastronomia italiana e principalmente pelas pizzas do forno a lenha. Em 2025 esteve presente na lista do pr\u00eamio <\/span><a href=\"https:\/\/arede.info\/publieditorial\/590756\/tomate-seco-e-indicado-como-um-dos-30-melhores-restaurantes-do-pr\"><span style=\"font-weight: 400\">Bom Gourmet<\/span><\/a><span style=\"font-weight: 400\">, que, de acordo com a professora de Turismo da Universidade Estadual de Ponta Grossa, Mirna de Lima Medeiros, \u00e9 um reconhecido pr\u00eamio gastron\u00f4mico do sul do pa\u00eds, que combina vota\u00e7\u00e3o do p\u00fablico com vota\u00e7\u00e3o de um j\u00fari t\u00e9cnico, e serve de guia ao consumidor na escolha de locais para visitar.<\/span><\/p>\n<div id=\"attachment_3210\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3210\" loading=\"lazy\" class=\"size-medium wp-image-3210\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-300x221.jpg\" alt=\"Foto: Emanueli Garcia\" width=\"300\" height=\"221\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-300x221.jpg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-1024x754.jpg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-768x566.jpg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-1536x1132.jpg 1536w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-2048x1509.jpg 2048w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-1232x908.jpg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanueli-Garcia-Gastronomia-1466x1080.jpg 1466w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3210\" class=\"wp-caption-text\">Foto: Emanueli Garcia<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Com um card\u00e1pio variado que vai dos frutos do mar, at\u00e9 pizza napolitana, o restaurante possui pratos diversificados para o agrado do cliente, sendo os carros chefe as pizzas de sabores originais especiale e cebola caramelizada, al\u00e9m dos pratos de massa com destaque para os ravi\u00f3lis e nhoques.\u00a0 Por\u00e9m para visitar o restaurante, o cliente deve ficar atento, pois mesmo com varia\u00e7\u00f5es nos valores,\u00a0 deve estar preparado para os custos do estabelecimento, pois estima-se um valor m\u00e9dio de R$80,00 por pessoa.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Al\u00e9m de uma variedade de pratos, o local conta com uma adega diversificada, indo do Malbec argentino ao Alicante Bouchest de Portugal. Por\u00e9m, aqueles que preferem apenas degustar de um Campo Largo adquirido no mercado, devem ficar atentos na cobran\u00e7a de um valor de R$70,00 pela rolha.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O restaurante disponibiliza locais reservados para aqueles que procuram calma na hora de comer. Com salas para eventos familiares ou de trabalho, \u00e9 poss\u00edvel realizar reservas antecipadas para ter acesso a locais mais espa\u00e7ados.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">No \u00faltimo m\u00eas, o bistr\u00f4 passou a disponibilizar almo\u00e7os de segunda a s\u00e1bado, al\u00e9m da janta, de ter\u00e7a a domingo, que \u00e9 a principal atra\u00e7\u00e3o, recebendo quase 600 visitantes apenas no final de semana.<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Emanueli Garcia<\/em><\/p>\n<p><strong>Servi\u00e7o<\/strong>: <span style=\"font-weight: 400\">Tomate Seco Bistr\u00f4, Rua Baldu\u00edno Taques 1029 &#8211; Estrela &#8211; Ponta Grossa PR.<\/span><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-3219 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4572.JPG-300x171.jpeg\" alt=\"\" width=\"277\" height=\"158\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4572.JPG-300x171.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4572.JPG-1024x583.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4572.JPG-768x437.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4572.JPG-1232x701.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4572.JPG.jpeg 1455w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/><\/p>\n<p style=\"text-align: center\"><b>Ascens\u00e3o do Streaming provoca queda de p\u00fablico nos cinemas<\/b><\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">A espera por filmes nas plataformas torna-se mais recorrente do que a ida ao cinema<\/span><\/i><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O n\u00famero de espectadores do cinema caiu cerca de 10% em Ponta Grossa de 2024 para 2025, o dado \u00e9 da<\/span> <span style=\"font-weight: 400\">Ag\u00eancia Nacional do Cinema (Ancine). Atualmente, a cidade conta com um cinema em funcionamento, no Shopping Palladium. Outra unidade ser\u00e1 aberta no Shopping Plaza Campos Gerais ainda no primeiro semestre de 2026.\u00a0<\/span><\/p>\n<div id=\"attachment_3212\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3212\" loading=\"lazy\" class=\"size-medium wp-image-3212\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanuelle-Pasqualotto-Imagem_-divulgacao-300x182.jpg\" alt=\"Foto: Divulga\u00e7\u00e3o\" width=\"300\" height=\"182\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanuelle-Pasqualotto-Imagem_-divulgacao-300x182.jpg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Emanuelle-Pasqualotto-Imagem_-divulgacao.jpg 534w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-3212\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">No mercado, o Streaming j\u00e1 ultrapassou os 100 bilh\u00f5es de d\u00f3lares, segundo a plataforma de dados Statista. O relat\u00f3rio anual mostra a quantidade de assinantes das maiores plataformas: Netflix com 260 milh\u00f5es, Amazon Prime Video 200 milh\u00f5es e Disney com 150 milh\u00f5es de usu\u00e1rios. Uma pesquisa da Nexus aponta que 7 a cada 10 brasileiros das classes alta, m\u00e9dia e baixa consomem algum streaming.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">O cinema j\u00e1 n\u00e3o \u00e9 a primeira op\u00e7\u00e3o para assistir filmes. O filme \u201cO Agente Secreto\u201d reuniu aproximadamente 500 espectadores durante novembro de 2025 em todas as exibi\u00e7\u00f5es na cidade, segundo a Ancine. A m\u00e9dia de <\/span><a href=\"https:\/\/www.ingresso.com\/cinema\/cine-araujo-ponta-grossa\"><span style=\"font-weight: 400\">pre\u00e7o da entrada<\/span><\/a><span style=\"font-weight: 400\"> inteira em Ponta Grossa \u00e9 R$46,60 e a meia entrada R$23,30<\/span><span style=\"font-weight: 400\">.<\/span><span style=\"font-weight: 400\"> Enquanto isso, o\u00a0 plano mais b\u00e1sico da Netflix est\u00e1 dispon\u00edvel por R$20,90 por m\u00eas.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Em m\u00e9dia, <\/span><span style=\"font-weight: 400\">35% dos brasileiros gastam at\u00e9 R$50,00 c<\/span><span style=\"font-weight: 400\">om streamings de v\u00eddeo, o que equivale a cerca de duas assinaturas.<\/span><span style=\"font-weight: 400\"> O ato de esperar os filmes serem lan\u00e7ados no streaming j\u00e1 se tornou algo comum entre as pessoas, eles representam 81% dos produtos mais assistidos nas plataformas.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Isso muda a forma como os filmes s\u00e3o valorizados, a ida ao cinema n\u00e3o \u00e9 mais um evento, mas sim, a espera de um filme no cat\u00e1logo. A desvaloriza\u00e7\u00e3o cinematogr\u00e1fica impacta a cultura desde os n\u00fameros das bilheterias at\u00e9 a forma de como o conte\u00fado \u00e9 consumido.\u00a0<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Emanuelle Pasqualotto<\/em><\/p>\n<p><b>Servi\u00e7o<\/b><span style=\"font-weight: 400\">: H\u00e1bito de (n\u00e3o) ir ao cinema em PG, cerca de 500 pessoas assistiram O Agente Secreto.<\/span><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-3215 aligncenter\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4568.JPG-300x166.jpeg\" alt=\"\" width=\"241\" height=\"133\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4568.JPG-300x166.jpeg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4568.JPG-1024x566.jpeg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4568.JPG-768x424.jpeg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4568.JPG-1232x681.jpeg 1232w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/IMG_4568.JPG.jpeg 1499w\" sizes=\"(max-width: 241px) 100vw, 241px\" \/><\/p>\n<p style=\"text-align: center\"><b>A volta da cintura baixa: nostalgia ou armadilha?<\/b><\/p>\n<p style=\"text-align: center\"><em><span style=\"font-weight: 400\">O estilo Y2K conquistou a nova gera\u00e7\u00e3o e se espalhou pelas redes, mas trouxe consigo a volta da press\u00e3o est\u00e9tica<\/span><\/em><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A tend\u00eancia anos 2.000 est\u00e1 de volta a todo vapor, e com ela as ic\u00f4nicas cal\u00e7as cintura baixa voltaram \u00e0s ruas. O que era vestimenta do dia a dia ou at\u00e9 mesmo considerado \u201cbrega\u201d agora \u00e9 chamada de estilo Y2K pela gera\u00e7\u00e3o Z. A procura pela cal\u00e7a teve um grande aumento, tanto em lojas online quanto f\u00edsicas, mas o grande protagonismo fica para a procura em brech\u00f3s. Em Ponta Grossa, a pe\u00e7a em brech\u00f3s tem um pre\u00e7o vari\u00e1vel de no m\u00e1ximo R$100.<\/span><\/p>\n<div id=\"attachment_3211\" style=\"width: 342px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-3211\" loading=\"lazy\" class=\" wp-image-3211\" src=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Sarah-Brasil-Creditos_-Reproducao_@marimeneezes_-no-Instagram-300x198.jpg\" alt=\"Foto: Reprodu\u00e7\u00e3o\/Instagram @marimenezees_\" width=\"332\" height=\"219\" srcset=\"https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Sarah-Brasil-Creditos_-Reproducao_@marimeneezes_-no-Instagram-300x198.jpg 300w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Sarah-Brasil-Creditos_-Reproducao_@marimeneezes_-no-Instagram-1024x676.jpg 1024w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Sarah-Brasil-Creditos_-Reproducao_@marimeneezes_-no-Instagram-768x507.jpg 768w, https:\/\/www2.uepg.br\/periodico\/wp-content\/uploads\/sites\/282\/2026\/04\/Sarah-Brasil-Creditos_-Reproducao_@marimeneezes_-no-Instagram.jpg 1080w\" sizes=\"(max-width: 332px) 100vw, 332px\" \/><p id=\"caption-attachment-3211\" class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o\/Instagram @marimenezees_<\/p><\/div>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A cal\u00e7a que lan\u00e7ava tend\u00eancia em revistas e em looks de grandes estrelas, como Britney Spears, Christina Aguilera, Beyonc\u00e9, e Paris Hilton, agora \u00e9 item indispens\u00e1vel no guarda roupa do p\u00fablico feminino. A cal\u00e7a tamb\u00e9m \u00e9 figurinha carimbada em v\u00eddeos virais no TikTok e Instagram, onde influenciadoras t\u00eam mostrado novas formas de usar a pe\u00e7a.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">A cintura baixa passou por algumas atualiza\u00e7\u00f5es como as modelagens mais amplas e as novas varia\u00e7\u00f5es, como cargo e wide leg, o que traz um visual mais moderno e urbano. Com sua cara nova, grifes como Diesel, Coperni e Miu Miu j\u00e1 est\u00e3o mostrando essa tend\u00eancia nas passarelas.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Mas para caber nessa cal\u00e7a um padr\u00e3o foi estabelecido. N\u00e3o foi apenas a cintura baixa que voltou direto dos anos 2.000, mas com ela o padr\u00e3o inalcan\u00e7\u00e1vel da magreza voltou a ser normalizado. A barriga \u201cchapada\u201d se tornou um pr\u00e9-requisito para vestir a cal\u00e7a.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-weight: 400\">Ultimamente em premia\u00e7\u00f5es, tapetes vermelhos e redes sociais o emagrecimento em massa se tornou normal e algo esbanjado. Assim os corpos reais viraram piada on-line e foram fortemente proibidos de usar a cal\u00e7a, fazendo as barriguinhas virarem tabu. Essa onda de magreza\u00a0 traz em foco o uso de rem\u00e9dios, dietas extremas e restri\u00e7\u00e3o alimentar como sin\u00f4nimo de beleza.\u00a0<\/span><\/p>\n<p style=\"text-align: right\"><em>Por Sarah Brasil<\/em><\/p>\n<p><strong>Servi\u00e7o<\/strong>: Em Ponta Grossa, as cal\u00e7as podem ser encontradas em brech\u00f3s, como a Dig For Fashion, por pre\u00e7os que chegam, em m\u00e9dia, at\u00e9 R$100.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left\"><b>Ficha t\u00e9cnica<\/b><\/p>\n<p style=\"text-align: left\"><b>Autores: <\/b>Amanda Los, Amanda Rafaella, Bruna Sluzala, Daniel Am\u00e9rico, Emanueli Garcia, Emanuelle Pasqualotto e Sarah Brasil<\/p>\n<p style=\"text-align: left\"><b>Supervis\u00e3o de produ\u00e7\u00e3o:<\/b>\u00a0 Paula Melani Rocha e S\u00e9rgio Luiz Gadini<\/p>\n<p style=\"text-align: left\"><b>Edi\u00e7\u00e3o e publica\u00e7\u00e3o:<\/b> Giulia Neves e Ticyane Almeida<\/p>\n<p style=\"text-align: left\"><b>Supervis\u00e3o de publica\u00e7\u00e3o:<\/b> Aline Rosso e Kevin Kossar Furtado<\/p>\n<p style=\"text-align: left\"><b>Contato:<\/b> periodico@uepg.br<\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00edtica de Ponta Produzido pelo terceiro ano do curso de Jornalismo da UEPG, o Cr\u00edtica de Ponta traz o melhor da cultura da cidade de Ponta Grossa para voc\u00ea! \u201cAinda assim, eu me levanto\u201d Levante de Lilah Halla exp\u00f5e realidade do direito ao aborto no Brasil O primeiro filme da diretora de cinema brasileira Lillah&nbsp;&hellip;<\/p>\n","protected":false},"author":933,"featured_media":3222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,8,2],"tags":[84,85],"_links":{"self":[{"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/posts\/3205"}],"collection":[{"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/users\/933"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/comments?post=3205"}],"version-history":[{"count":11,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/posts\/3205\/revisions"}],"predecessor-version":[{"id":3523,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/posts\/3205\/revisions\/3523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/media\/3222"}],"wp:attachment":[{"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/media?parent=3205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/categories?post=3205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.uepg.br\/periodico\/wp-json\/wp\/v2\/tags?post=3205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}